{"id":434,"count":1,"description":"","link":"https:\/\/pamelarussell.org\/teach\/tag\/lamentations-325\/","name":"Lamentations 3:25","slug":"lamentations-325","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/pamelarussell.org\/teach\/wp-json\/wp\/v2\/tags\/434"}],"collection":[{"href":"https:\/\/pamelarussell.org\/teach\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/pamelarussell.org\/teach\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/pamelarussell.org\/teach\/wp-json\/wp\/v2\/posts?tags=434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}